{"id":86987,"date":"2026-03-03T17:10:01","date_gmt":"2026-03-03T16:10:01","guid":{"rendered":"https:\/\/www.santacole.com\/project\/ll731\/"},"modified":"2026-05-07T16:06:43","modified_gmt":"2026-05-07T14:06:43","slug":"ll731","status":"publish","type":"project","link":"https:\/\/www.santacole.com\/es\/project\/ll731\/","title":{"rendered":"LL731"},"content":{"rendered":"\n<div class=\"block-header pt-sc-layout-grid-padding-column-rythm-xl pb-sc-spacing-padding-sm align wp-block-santacole-block-section-header\">\n\n    \n            <div class=\"px-sc-spacing-padding-md\">\n\n                <div class=\"pb-sc-spacing-padding-sm\">  \n                    <button class=\"sc-btn sc-button-sm sc-button-link\" type=\"button\">\n                        <a href=\"https:\/\/www.santacole.com\/en\/projects\/\" target=\"_self\" class=\"w-full h-full flex items-center justify-center\">\n                            <i class=\"!text-base icon-arrow-left\"><\/i>\n                            <span class=\"flex align-items-center\">\n                                Ver todos los proyectos                            <\/span>\n                        <\/a>\n                    <\/button>\n                <\/div>\n\n                <div>\n                    <h2 style=\"font-style:normal;font-weight:400;line-height:1.2;\" class=\"wp-block-post-title has-h-2-font-size\">\n                        Archivos                    <\/h2>\n\n                    \n                            <p class=\"font-medium has-md-font-size\">\n                                Barcelona, Espa\u00f1a                            <\/p>\n                                        <\/div>\n                    \n            <\/div>\n\n            \n<\/div>\n<div class=\"wp-block-group scroll-fade-in is-layout-constrained wp-container-core-group-is-layout-20acb5f8 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--md);padding-bottom:var(--wp--preset--spacing--rythm-sm);padding-left:var(--wp--preset--spacing--md)\">\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-2\/1 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/ll31-2.jpg\" class=\"  w-full h-full object-cover\" alt=\"ll31-2\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/ll31-2.jpg 2560w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/ll31-2-600x450.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/ll31-2-1280x960.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/ll31-2-300x225.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/ll31-2-768x576.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/ll31-2-1200x900.jpg 1200w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n    \n\n\n<\/div>\n\n<div class=\"wp-block-group scroll-fade-in is-layout-constrained wp-container-core-group-is-layout-fd9ebb69 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--rythm-lg);padding-left:var(--wp--preset--spacing--md)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-42e9c677 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-37505225 wp-block-group-is-layout-flex\">\n<p class=\"has-sm-font-size\" style=\"font-weight:600\">Categor\u00eda:<\/p>\n\n\n<div style=\"font-weight:400\" class=\"taxonomy-project-category wp-block-post-terms has-sm-font-size\"><a href=\"https:\/\/www.santacole.com\/es\/categoria-proyecto\/residencial\/\" rel=\"tag\">Residencial<\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-37505225 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-sm-font-size\" style=\"font-weight:600\">Dise\u00f1o:<\/p>\n<\/div>\n\n\n\n<p class=\"has-sm-font-size\" style=\"font-weight:400\"><a href=\"https:\/\/arame-studio.com\/\" data-type=\"link\" data-id=\"https:\/\/arame-studio.com\/\" rel=\"nofollow noopener\" target=\"_blank\">Aram\u00e9 Studio<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-37505225 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-sm-font-size\" style=\"font-weight:600\">Fotograf\u00eda:<\/p>\n<\/div>\n\n\n\n<p class=\"has-sm-font-size\" style=\"font-weight:400\"><a href=\"https:\/\/delriobani.com\/?g=paradigma-cs\" data-type=\"link\" data-id=\"https:\/\/delriobani.com\/?g=paradigma-cs\" rel=\"nofollow noopener\" target=\"_blank\">Bani del R\u00edo<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-bottom:1em\"><div style=\"font-style:normal;font-weight:700;\" class=\"wp-block-post-excerpt has-md-font-size\"><p class=\"wp-block-post-excerpt__excerpt\">Renovaci\u00f3n de la Casa Jaume Bach Esteve. <\/p><\/div><\/div>\n\n\n\n<p class=\"has-md-font-size\">La casa Jaume Bach Esteve es una construcci\u00f3n de principios del siglo XX situada en el barrio de Poblenou, Barcelona. El arquitecto Raimon Batlle i Maga\u00f1as la proyect\u00f3 en 1903 en un estilo modernista muy austero. En el aspecto decorativo, destaca por su fachada con dinteles esculpidos y m\u00e9nsulas bajo el balc\u00f3n, ambos con relieves florales, rejas de hierro forjado, barandillas de hierro fundido y puertas de madera.  <\/p>\n\n\n\n<p class=\"has-md-font-size\">Partiendo de esta base, el despacho de arquitectura encargado de su renovaci\u00f3n, Aram\u00e9 Studio (Andrea Arriola Fiol y Adri\u00e1n Mellado Mu\u00f1oz), se ha guiado por un profundo respeto por la arquitectura original y la ha transformado con una especie de sobriedad contenida, permitiendo que la estructura existente mantenga su presencia, a la vez que introduce un lenguaje contempor\u00e1neo y preciso. La casa, que en su d\u00eda estaba compuesta por dos apartamentos separados, consta de 250 m2 y reinventa el edificio como una vivienda unifamiliar m\u00e1s estudio distribuida en dos plantas.   <\/p>\n\n\n\n<p class=\"has-md-font-size\">La est\u00e9tica minimalista general prioriza la claridad sobre el espect\u00e1culo. En su interior reina un silencio decorativo, casi mon\u00e1stico, con espacios ligeros, fluidos y generosos entre los que siempre parece circular el aire. Superficies de acero inoxidable, madera, elementos a medida, sencillez, buen hacer y una paleta neutra y limpia se extienden por las estancias como intervenciones escult\u00f3ricas. En contraste, las b\u00f3vedas encaladas del hueco de la escalera hablan de la historia y del pasado. Arriba, la terraza ampl\u00eda la l\u00f3gica austera y funcional del proyecto, con paredes sin revestir y persianas ajustables. Abajo, encima de la mesa de madera, pende un ejemplar del modelo L\u00e1mina Mayor de Antoni Arola.     <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<div style=\"height:var(--wp--preset--spacing--rythm-xl)\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-group scroll-fade-in is-layout-constrained wp-container-core-group-is-layout-3ece0061 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--lg);padding-bottom:var(--wp--preset--spacing--rythm-xl);padding-left:var(--wp--preset--spacing--lg)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9c22b1e3 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-3\/4 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n    \n        <a class=\"w-full h-full\" href=\"https:\/\/www.santacole.com\/es\/iluminacion\/lamparas-de-suspension\/lamina-mayor-lampf01\/\" target=\"\">\n\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"1280\" height=\"1280\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_10_1-1280x1280.jpg\" class=\"  w-full h-full object-cover\" alt=\"BDR_2025_ARAME_Lull_10_1\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_10_1-1280x1280.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_10_1-600x600.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_10_1-300x300.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_10_1-768x768.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_10_1-400x400.jpg 400w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_10_1-1200x1200.jpg 1200w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_10_1-100x100.jpg 100w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n            <\/a>\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n            <div class=\"bg-sc-color-primary-foreground px-2.5 py-1.5 w-fit !mt-0\">\n            <p class=\"text-sc-color-foreground text-xs\" >L\u00e1mina Mayor<\/p>\n        <\/div>\n    \n\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-group scroll-fade-in is-layout-constrained wp-container-core-group-is-layout-6e25b6d0 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--md);padding-bottom:var(--wp--preset--spacing--rythm-xl);padding-left:var(--wp--preset--spacing--md)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center has-h-4-font-size\" style=\"line-height:1.2\">Bajo una fina l\u00e1mina blanca, un subrayado de luz, tenue pero eficaz. Aqu\u00ed la luz no solo ilumina, estructura y define el entorno, en un gesto sutil pero a la vez poderoso. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-group scroll-fade-in is-layout-constrained wp-container-core-group-is-layout-3ece0061 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--lg);padding-bottom:var(--wp--preset--spacing--rythm-xl);padding-left:var(--wp--preset--spacing--lg)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-3\/4 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"1280\" height=\"1279\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-23-x2400-1280x1279.jpg\" class=\"  w-full h-full object-cover\" alt=\"BDR-2025-ARAME-Lull-23-x2400\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-23-x2400-1280x1279.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-23-x2400-600x600.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-23-x2400-300x300.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-23-x2400-768x768.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-23-x2400-400x400.jpg 400w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-23-x2400-1200x1200.jpg 1200w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-23-x2400-100x100.jpg 100w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n    \n\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<div class=\"wp-block-columns are-vertically-aligned-center h-full is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center scroll-fade-in is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-3\/4 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"1280\" height=\"1280\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_27_1-1280x1280.jpg\" class=\"  w-full h-full object-cover\" alt=\"BDR_2025_ARAME_Lull_27_1\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_27_1-1280x1280.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_27_1-600x600.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_27_1-300x300.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_27_1-768x768.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_27_1-400x400.jpg 400w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_27_1-1200x1200.jpg 1200w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR_2025_ARAME_Lull_27_1-100x100.jpg 100w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n    \n\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-group scroll-fade-in is-layout-constrained wp-container-core-group-is-layout-6e25b6d0 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--md);padding-bottom:var(--wp--preset--spacing--rythm-xl);padding-left:var(--wp--preset--spacing--md)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center has-h-4-font-size\" style=\"line-height:1.2\">El proyecto se concibe como una continuidad de estancias sin divisiones fijas que generan un espacio flexible y adaptable, donde es el mobiliario el que define el uso de cada zona, y no los tabiques. El tema principal es la mezcla entre los elementos antiguos y las nuevas incorporaciones que cohabitan en una tensi\u00f3n natural, enriqueciendo as\u00ed la identidad del espacio, que ahora se siente a la vez arraigado pero libre. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-group scroll-fade-in is-layout-constrained wp-container-core-group-is-layout-3ece0061 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--lg);padding-bottom:var(--wp--preset--spacing--rythm-xl);padding-left:var(--wp--preset--spacing--lg)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<div class=\"wp-block-columns are-vertically-aligned-center h-full is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center scroll-fade-in is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-3\/4 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"1280\" height=\"1280\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-28-x2400-1280x1280.jpg\" class=\"  w-full h-full object-cover\" alt=\"BDR-2025-ARAME-Lull-28-x2400\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-28-x2400-1280x1280.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-28-x2400-600x600.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-28-x2400-300x300.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-28-x2400-768x768.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-28-x2400-400x400.jpg 400w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-28-x2400-1200x1200.jpg 1200w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-28-x2400-100x100.jpg 100w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n    \n\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-3\/4 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"1280\" height=\"1280\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-31-x2400-1280x1280.jpg\" class=\"  w-full h-full object-cover\" alt=\"BDR-2025-ARAME-Lull-31-x2400\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-31-x2400-1280x1280.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-31-x2400-600x600.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-31-x2400-300x300.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-31-x2400-768x768.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-31-x2400-400x400.jpg 400w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-31-x2400-1200x1200.jpg 1200w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/BDR-2025-ARAME-Lull-31-x2400-100x100.jpg 100w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n    \n\n\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Renovaci\u00f3n de la Casa Jaume Bach Esteve.<\/p>\n","protected":false},"featured_media":86965,"parent":0,"template":"","project-category":[1637],"class_list":["post-86987","project","type-project","status-publish","has-post-thumbnail","hentry","project-category-residencial","entry"],"acf":{"project_location":{"country":"Espa\u00f1a","city":"Barcelona"}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Santa &amp; Cole","distributor_original_site_url":"https:\/\/www.santacole.com\/es\/","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.santacole.com\/es\/wp-json\/wp\/v2\/project\/86987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacole.com\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.santacole.com\/es\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacole.com\/es\/wp-json\/wp\/v2\/media\/86965"}],"wp:attachment":[{"href":"https:\/\/www.santacole.com\/es\/wp-json\/wp\/v2\/media?parent=86987"}],"wp:term":[{"taxonomy":"project-category","embeddable":true,"href":"https:\/\/www.santacole.com\/es\/wp-json\/wp\/v2\/project-category?post=86987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}