{"id":112278,"date":"2026-03-28T10:03:14","date_gmt":"2026-03-28T09:03:14","guid":{"rendered":"https:\/\/www.santacole.com\/?post_type=project&#038;p=112278"},"modified":"2026-03-28T13:15:29","modified_gmt":"2026-03-28T12:15:29","slug":"akhaldaba-private-house","status":"publish","type":"project","link":"https:\/\/www.santacole.com\/en\/project\/akhaldaba-private-house\/","title":{"rendered":"Akhaldaba Private House"},"content":{"rendered":"\n<div class=\"block-header pt-sc-layout-grid-padding-column-rythm-xl pb-sc-spacing-padding-sm align wp-block-santacole-block-section-header\">\n\n    \n            <div class=\"px-sc-spacing-padding-md\">\n\n                <div class=\"pb-sc-spacing-padding-sm\">  \n                    <button class=\"sc-btn sc-button-sm sc-button-link\" type=\"button\">\n                        <a href=\"https:\/\/www.santacole.com\/en\/projects\/\" target=\"_self\" class=\"w-full h-full flex items-center justify-center\">\n                            <i class=\"!text-base icon-arrow-left\"><\/i>\n                            <span class=\"flex align-items-center\">\n                                View all Projects                            <\/span>\n                        <\/a>\n                    <\/button>\n                <\/div>\n\n                <div>\n                    <h2 style=\"font-style:normal;font-weight:400;line-height:1.2;\" class=\"wp-block-post-title has-h-2-font-size\">\n                        Archives                    <\/h2>\n\n                    \n                            <p class=\"font-medium has-md-font-size\">\n                                                            <\/p>\n                                        <\/div>\n                    \n            <\/div>\n\n            \n<\/div>\n\n\n<div class=\"wp-block-group scroll-fade-in is-layout-constrained wp-container-core-group-is-layout-20acb5f8 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--md);padding-bottom:var(--wp--preset--spacing--rythm-sm);padding-left:var(--wp--preset--spacing--md)\">\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-16\/9 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"2400\" height=\"1800\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4349-1-x2400.jpg\" class=\"  w-full h-full object-cover\" alt=\"Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4349-1&#8211;x2400\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4349-1-x2400.jpg 2400w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4349-1-x2400-600x450.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4349-1-x2400-1280x960.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4349-1-x2400-300x225.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4349-1-x2400-768x576.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4349-1-x2400-1200x900.jpg 1200w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n    \n\n\n<\/div>\n\n\n\n<div class=\"wp-block-group scroll-fade-in is-layout-constrained wp-container-core-group-is-layout-fd9ebb69 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--rythm-lg);padding-left:var(--wp--preset--spacing--md)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-constrained wp-block-column-is-layout-constrained\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-9f186b9e wp-block-group-is-layout-flex\" style=\"padding-bottom:var(--wp--preset--spacing--rythm-md)\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-37505225 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-sm-font-size\" style=\"font-weight:600\">Category:<\/p>\n<\/div>\n\n\n<div style=\"font-weight:400;text-decoration:underline\" class=\"taxonomy-project-category sc-underline wp-block-post-terms has-sm-font-size\"><a href=\"https:\/\/www.santacole.com\/en\/project-category\/residential\/\" rel=\"tag\">Residential<\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-37505225 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-sm-font-size\" style=\"font-weight:600\">Design:<\/p>\n<\/div>\n\n\n\n<p class=\"has-sm-font-size\" style=\"font-weight:400\"><a href=\"https:\/\/mua.ge\/en\" data-type=\"link\" data-id=\"https:\/\/mua.ge\/en\" rel=\"nofollow noopener\" target=\"_blank\">MUA Architecture &amp; Placemaking<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-37505225 wp-block-group-is-layout-flex\">\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-sm-font-size\" style=\"font-weight:600\">Photography:<\/p>\n<\/div>\n\n\n\n<p class=\"has-sm-font-size\" style=\"font-weight:400\"><a href=\"https:\/\/www.instagram.com\/g_mamasakhlisi\/\" data-type=\"link\" data-id=\"https:\/\/www.instagram.com\/g_mamasakhlisi\/\" rel=\"nofollow noopener\" target=\"_blank\">Giorgi Mamasakhlisi<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-md-font-size\">In the remote mountain village of Akhaldaba, in Georgia, this single-family home is designed by MUA Architecture to integrate nature with harmony. Its location gives context and is a direct response to the site where it stands; architecture and landscape are part of the same process.<\/p>\n\n\n\n<p class=\"has-md-font-size\">With an exposed concrete fa\u00e7ade, green aluminum details, and climbing plants, the project answers to the complexity of the landscape through a structure of three interconnected volumes that follow the contours of the plot with a minimal intervention, preserving natural lines, and allowing the structure to settle organically. The layout ensures clarity and integration with the surroundings. The orientation and connection of these volumes was defined not only by their functional relationships but also by a strategy: to create semi-open spaces that further enhance the interaction between the built environment and nature. The proposal emphasizes sustainability and minimal environmental impact.<\/p>\n\n\n\n<p class=\"has-md-font-size\">With a total of 400 m\u00b2 over two floors, the spaces open strategically toward specific points in the landscape, seeking views, light, privacy, and a constant relationship with the outdoors. The intention was for each room to have a purpose and a visual connection with the its surroundings. Design and functionality were prioritized, with special attention to material selection and a raw yet harmonic aesthetic. Natural wood, soft lighting, and high-quality finishes create an elegant and welcoming atmosphere. The result is a contemporary architectural shape, a house that is both refuge and inspiration. Inside, level changes that mimic the ups and downs of the land translate into staircases connecting the three volumes and multiple routes to reach different spaces.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:var(--wp--preset--spacing--rythm-xl)\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-6e25b6d0 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--md);padding-bottom:var(--wp--preset--spacing--rythm-xl);padding-left:var(--wp--preset--spacing--md)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<div style=\"margin-top:var(--wp--preset--spacing--rythm-md);margin-bottom:var(--wp--preset--spacing--rythm-md);height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer hidden md:block\"><\/div>\n\n\n\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-3\/4 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"1280\" height=\"1707\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4142-1-x2400-1280x1707.jpg\" class=\"  w-full h-full object-cover\" alt=\"Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4142-1&#8211;x2400\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4142-1-x2400-1280x1707.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4142-1-x2400-600x800.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4142-1-x2400-300x400.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4142-1-x2400-768x1024.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4142-1-x2400-1200x1600.jpg 1200w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4142-1-x2400.jpg 1800w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n    \n\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-4\/3 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n    \n        <a class=\"w-full h-full\" href=\"https:\/\/www.santacole.com\/en\/lighting\/pendant-lamps\/gt7-380\/\" target=\"\">\n\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4096-x2400-1280x960.jpg\" class=\"  w-full h-full object-cover\" alt=\"Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4096-x2400\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4096-x2400-1280x960.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4096-x2400-600x450.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4096-x2400-300x225.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4096-x2400-768x576.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-MMS4096-x2400-1200x900.jpg 1200w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n            <\/a>\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n            <div class=\"bg-sc-color-primary-foreground px-2.5 py-1.5 w-fit !mt-0\">\n            <p class=\"text-sc-color-foreground text-xs\" >GT7 2000, Santa &amp; Cole Team.<\/p>\n        <\/div>\n    \n\n\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group scroll-fade-in is-layout-constrained wp-container-core-group-is-layout-6e25b6d0 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--md);padding-bottom:var(--wp--preset--spacing--rythm-xl);padding-left:var(--wp--preset--spacing--md)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center has-lead-font-size\">With wood as the dominant material, modernity, simplicity, and warmth, the kitchen stands out, fully open to the garden and hills. Here, the <strong>GT7<\/strong> pendant lamp, with its off-white ribboned drum shade that softens the light, creates a warm and decorative presence in the space. Beside them, on the countertop, are two <strong>L\u00e1mina 165<\/strong>, the longest and narrowest version of this lighting family, which celebrates the virtues of reflected light. Designed by Antoni Arola, it combines proportion with clarity, efficiency with lightness.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:15%\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-6e25b6d0 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--md);padding-bottom:var(--wp--preset--spacing--rythm-xl);padding-left:var(--wp--preset--spacing--md)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-2512d504 wp-block-columns-is-layout-flex\" style=\"padding-bottom:var(--wp--preset--spacing--rythm-lg)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:35%\">\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-4\/3 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4589-1-x2400-1280x960.jpg\" class=\"  w-full h-full object-cover\" alt=\"Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4589-1&#8211;x2400\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4589-1-x2400-1280x960.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4589-1-x2400-600x450.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4589-1-x2400-300x225.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4589-1-x2400-768x576.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4589-1-x2400-1200x900.jpg 1200w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n    \n\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:5%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:35%\">\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-4\/3 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4049-2-x2400-1280x960.jpg\" class=\"  w-full h-full object-cover\" alt=\"Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4049-2-x2400\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4049-2-x2400-1280x960.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4049-2-x2400-600x450.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4049-2-x2400-300x225.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4049-2-x2400-768x576.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4049-2-x2400-1200x900.jpg 1200w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n    \n\n\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-4\/3 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4533-x2400-1280x960.jpg\" class=\"  w-full h-full object-cover\" alt=\"Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4533-x2400\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4533-x2400-1280x960.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4533-x2400-600x450.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4533-x2400-300x225.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4533-x2400-768x576.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-MMS4533-x2400-1200x900.jpg 1200w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n    \n\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group scroll-fade-in is-layout-constrained wp-container-core-group-is-layout-3ece0061 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--lg);padding-bottom:var(--wp--preset--spacing--rythm-xl);padding-left:var(--wp--preset--spacing--lg)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9c22b1e3 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<div class=\"block-image group w-full relative !bg-sc-color-border  overflow-hidden aspect-3\/2 flex justify-center items-center\" style=\"\">\n\n    \n    <!-- Si hay link dentro del bloque imagen -->\n    \n        <a class=\"w-full h-full\" href=\"https:\/\/www.santacole.com\/en\/lighting\/pendant-lamps\/lamina-165-lampe01\/\" target=\"\">\n\n        \n    <!-- Simple -->\n    \n        <img decoding=\"async\" width=\"2400\" height=\"1800\" src=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-LAMINA-165-MMS4179-x2400.jpg\" class=\"  w-full h-full object-cover\" alt=\"Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-LAMINA-165-MMS4179-x2400\" sizes=\"100vw\" srcset=\"https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-LAMINA-165-MMS4179-x2400.jpg 2400w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-LAMINA-165-MMS4179-x2400-600x450.jpg 600w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-LAMINA-165-MMS4179-x2400-1280x960.jpg 1280w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-LAMINA-165-MMS4179-x2400-300x225.jpg 300w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-LAMINA-165-MMS4179-x2400-768x576.jpg 768w, https:\/\/www.santacole.com\/wp-content\/uploads\/2026\/03\/Akhaldaba-Private-House-Georgia-MUA-2023-Giorgi-Mamasakhlisi-GT7-LAMINA-165-MMS4179-x2400-1200x900.jpg 1200w\" loading=\"lazy\" \/>        \n        <!-- Caption inside -->\n        \n    \n    <!-- Hover overlay -->\n    \n    <!-- Slider gallery -->\n    \n    <!-- Si hay link cierre -->\n            <\/a>\n    \n<\/div>\n\n<!-- Simple (Caption outside) -->\n    \n    <!-- Caption outside -->\n            <div class=\"bg-sc-color-primary-foreground px-2.5 py-1.5 w-fit !mt-0\">\n            <p class=\"text-sc-color-foreground text-xs\" >L\u00e1mina 165 2018, Antoni Arola.<\/p>\n        <\/div>\n    \n\n\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Category: Design: MUA Architecture &amp; Placemaking Photography: Giorgi Mamasakhlisi In the remote mountain village of Akhaldaba, in Georgia, this single-family home is designed by MUA Architecture to integrate nature with harmony. Its location gives context and is a direct response to the site where it stands; architecture and landscape are part of the same process. [&hellip;]<\/p>\n","protected":false},"featured_media":112282,"parent":0,"template":"","project-category":[1631],"class_list":["post-112278","project","type-project","status-publish","has-post-thumbnail","hentry","project-category-residential","entry"],"acf":{"project_location":{"country":"","city":""}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Santa &amp; Cole","distributor_original_site_url":"https:\/\/www.santacole.com\/en\/","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.santacole.com\/en\/wp-json\/wp\/v2\/project\/112278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacole.com\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.santacole.com\/en\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacole.com\/en\/wp-json\/wp\/v2\/media\/112282"}],"wp:attachment":[{"href":"https:\/\/www.santacole.com\/en\/wp-json\/wp\/v2\/media?parent=112278"}],"wp:term":[{"taxonomy":"project-category","embeddable":true,"href":"https:\/\/www.santacole.com\/en\/wp-json\/wp\/v2\/project-category?post=112278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}